{"id":8487,"date":"2024-01-07T21:45:56","date_gmt":"2024-01-07T20:45:56","guid":{"rendered":"https:\/\/christliche-mitte.de\/?p=8487"},"modified":"2024-01-07T21:45:58","modified_gmt":"2024-01-07T20:45:58","slug":"gesegnetes-neujahr","status":"publish","type":"post","link":"https:\/\/christliche-mitte.de\/index.php\/2024\/01\/07\/gesegnetes-neujahr\/","title":{"rendered":"Gesegnetes Neujahr!"},"content":{"rendered":"\n<p><strong>Mit GOTT durch 2024.<\/strong> Was auch immer kommen mag, GOTT h\u00e4lt alles in Seinen H\u00e4nden. <br>Ein gro\u00dfes Vergelt\u00b4s GOTT an Sie, liebe KURIER-Leser, f\u00fcr Ihre gro\u00dfherzigen Weihnachts-Spenden.<\/p>\n\n\n\n<p>Nehmen wir alle Dinge, die uns in diesem Jahr begegnen, vertrauensvoll in GOTT an: Frieden oder auch die Zuspitzung des Krieges und vor allem die aus dem Gleis laufende Welt-Synode. Beten wir f\u00fcr die Irregeleiteten. <br>GOTT ist st\u00e4rker als der Krieg. Bleiben Sie der alten Liturgie treu, beten Sie jeden Tag den Rosenkranz und empfangen Sie die Sakramente. <br>Denn: \u201eBei GOTT ist kein Ding unm\u00f6glich!\u201c (Lk 1,37).<br><br>Buch: <strong><a href=\"https:\/\/christliche-mitte.de\/index.php\/produkt\/himmelsleiter\/\" data-type=\"product\" data-id=\"5276\">Himmelsleiter<\/a><\/strong> (10 \u20ac)<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"480\" style=\"aspect-ratio: 848 \/ 480;\" width=\"848\" controls src=\"https:\/\/christliche-mitte.de\/wp-content\/uploads\/2024\/01\/VIDEO-27-11-23.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Mit GOTT durch 2024. Was auch immer kommen mag, GOTT h\u00e4lt alles in Seinen H\u00e4nden. Ein gro\u00dfes Vergelt\u00b4s GOTT an Sie, liebe KURIER-Leser, f\u00fcr Ihre gro\u00dfherzigen Weihnachts-Spenden. Nehmen wir alle Dinge, die uns in diesem Jahr begegnen, vertrauensvoll in GOTT an: Frieden oder auch die Zuspitzung des Krieges und vor allem die aus dem Gleis&hellip;<\/p>\n","protected":false},"author":1,"featured_media":8489,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,4],"tags":[],"class_list":["post-8487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-christus-glaube","category-kurier-der-christlichen-mitte","entry"],"_links":{"self":[{"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/posts\/8487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/comments?post=8487"}],"version-history":[{"count":1,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/posts\/8487\/revisions"}],"predecessor-version":[{"id":8490,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/posts\/8487\/revisions\/8490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/media\/8489"}],"wp:attachment":[{"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/media?parent=8487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/categories?post=8487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/tags?post=8487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}