{"id":7218,"date":"2023-01-11T21:02:18","date_gmt":"2023-01-11T19:02:18","guid":{"rendered":"https:\/\/christliche-mitte.de\/?p=7218"},"modified":"2023-01-11T21:02:23","modified_gmt":"2023-01-11T19:02:23","slug":"lukaschenko-inhaftiert-jugendliche","status":"publish","type":"post","link":"https:\/\/christliche-mitte.de\/index.php\/2023\/01\/11\/lukaschenko-inhaftiert-jugendliche\/","title":{"rendered":"Lukaschenko inhaftiert Jugendliche"},"content":{"rendered":"\n<p>Der Diktator von Belarus, Pr\u00e4sident Alexander Lukaschenko, l\u00e4\u00dft jugendliche Demonstranten einsperren, und zwar seit Jahren.<\/p>\n\n\n\n<p>Zum Beispiel Nikita Zalatarou (16). Vor 2 Jahren wurde der Jugendliche verhaftet, bewu\u00dftlos geschlagen und erst tags darauf in einer Intensiv-Station untersucht. Obwohl er seine Unschuld beteuert, wird er zu viereinhalb Jahren Gef\u00e4ngnis verurteilt \u201ewegen b\u00f6swilligen Rowdytums\u201c. Unabh\u00e4ngige Untersucher stellen fest: Alexander war an den vorgeworfenen Verbrechen nicht beteiligt. Deshalb erkennen ihn die IGFM-Menschenrechtler als politischen Ge\u00adfangenen an. Beim Verh\u00f6r wird er jeden Tag auf den Hinterkopf geschlagen. Seine Epilepsie wird in der Haft nicht ausreichend behandelt. Die viereinhalb Jahre mu\u00df Alexander in Bobrujsk\/Belarus verb\u00fc\u00dfen, Ju\u00adgendstrafanstalt Nr. 2. <br>Buch: <a href=\"https:\/\/christliche-mitte.de\/index.php\/buch-ueber-telefon-oder-per-mail-bestellbar\/\" data-type=\"page\" data-id=\"6540\">Briefe von zum Tode Verurteilter 1939-1945<\/a> (10 \u20ac).<br><a href=\"https:\/\/christliche-mitte.de\/index.php\/buch-ueber-telefon-oder-per-mail-bestellbar\/\" data-type=\"page\" data-id=\"6540\">Brie\u00adfe aus dem 30j\u00e4hrigen Krieg <\/a>(10 \u20ac)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Diktator von Belarus, Pr\u00e4sident Alexander Lukaschenko, l\u00e4\u00dft jugendliche Demonstranten einsperren, und zwar seit Jahren. Zum Beispiel Nikita Zalatarou (16). Vor 2 Jahren wurde der Jugendliche verhaftet, bewu\u00dftlos geschlagen und erst tags darauf in einer Intensiv-Station untersucht. Obwohl er seine Unschuld beteuert, wird er zu viereinhalb Jahren Gef\u00e4ngnis verurteilt \u201ewegen b\u00f6swilligen Rowdytums\u201c. Unabh\u00e4ngige Untersucher stellen&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72,4],"tags":[],"class_list":["post-7218","post","type-post","status-publish","format-standard","hentry","category-informationen-aus-der-politik","category-kurier-der-christlichen-mitte","no-post-thumbnail","entry"],"_links":{"self":[{"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/posts\/7218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/comments?post=7218"}],"version-history":[{"count":1,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/posts\/7218\/revisions"}],"predecessor-version":[{"id":7219,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/posts\/7218\/revisions\/7219"}],"wp:attachment":[{"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/media?parent=7218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/categories?post=7218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/tags?post=7218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}