{"id":4544,"date":"2020-10-29T22:44:11","date_gmt":"2020-10-29T20:44:11","guid":{"rendered":"https:\/\/christliche-mitte.de\/?p=4544"},"modified":"2020-10-29T22:44:12","modified_gmt":"2020-10-29T20:44:12","slug":"extremismus-in-deutschland","status":"publish","type":"post","link":"https:\/\/christliche-mitte.de\/index.php\/2020\/10\/29\/extremismus-in-deutschland\/","title":{"rendered":"Extremismus in Deutschland"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Den 32.000 Rechts-Extremisten stehen 33.500 Links-Extremisten gegen\u00fcber. 28.000 Islamisten sind gleichfalls aktiv, doch gab es seit 3 Jahren keinen Anschlag mehr. Alle Gruppen haben jedoch Zuwachs, am st\u00e4rksten die Linken, am meisten die Salafisten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie wollen das Leben der islamischen Urzeit in unsere Welt hineinpflanzen. Wie vorgeschrieben, nehmen sie den Koran wortw\u00f6rtlich. Das f\u00fchrt hin zum Dschihadismus, zum Terrorismus. Die in Deutschland entlarvten Terrorgruppen waren zumeist von Salafisten gen\u00e4hrt. Der Verfassungsschutz z\u00e4hlt mehr als 11.000 hierzulande. Doch Salafisten arbeiten auch l\u00e4nder\u00fcbergreifend.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Den 32.000 Rechts-Extremisten stehen 33.500 Links-Extremisten gegen\u00fcber. 28.000 Islamisten sind gleichfalls aktiv, doch gab es seit 3 Jahren keinen Anschlag mehr. Alle Gruppen haben jedoch Zuwachs, am st\u00e4rksten die Linken, am meisten die Salafisten. Sie wollen das Leben der islamischen Urzeit in unsere Welt hineinpflanzen. Wie vorgeschrieben, nehmen sie den Koran wortw\u00f6rtlich. Das f\u00fchrt hin&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,72,4],"tags":[],"class_list":["post-4544","post","type-post","status-publish","format-standard","hentry","category-islam","category-informationen-aus-der-politik","category-kurier-der-christlichen-mitte","no-post-thumbnail","entry"],"_links":{"self":[{"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/posts\/4544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/comments?post=4544"}],"version-history":[{"count":1,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/posts\/4544\/revisions"}],"predecessor-version":[{"id":4545,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/posts\/4544\/revisions\/4545"}],"wp:attachment":[{"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/media?parent=4544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/categories?post=4544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/christliche-mitte.de\/index.php\/wp-json\/wp\/v2\/tags?post=4544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}